{"id":6693,"date":"2020-02-06T09:06:20","date_gmt":"2020-02-06T08:06:20","guid":{"rendered":"https:\/\/www.ilcf.net\/?p=6693"},"modified":"2020-02-06T09:12:41","modified_gmt":"2020-02-06T08:12:41","slug":"tandems-linguistiques-ilcf-esqese","status":"publish","type":"post","link":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/","title":{"rendered":"Tandems linguistiques ILCF \/ ESQESE"},"content":{"rendered":"<div class=\"wp-block-text-image\">\n  <div class=\"row align-bottom collapse\">\n    <div class=\"column small-12 medium-6 xlarge-5 xxlarge-expand wp-block-text-image-info js-fade-scroll\">\n      <p class=\"wp-block-text-image-title\">Premi\u00e8re rencontre du tandem ESQESE\/ILCF<\/p>\n      <div class=\"wp-block-text-image-intro\"><p>La premi\u00e8re rencontre des \u00e9tudiants a \u00e9t\u00e9 un succ\u00e8s. Les photos en t\u00e9moignent. C\u2019est avec curiosit\u00e9, plaisir et enthousiasme qu\u2019\u00e9tudiants et enseignants vivent ce nouveau partenariat !<\/p>\n<\/div>\n    <\/div>\n\n    <div class=\"column small-12 medium-6 xlarge-7 xxlarge-shrink wp-block-text-image-picture js-fade-scroll\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"525\" src=\"https:\/\/www.ilcf.net\/wp-content\/uploads\/sites\/20\/2019\/11\/tandem-linguistique-esqese-ilcf-2017-ilcf-web.jpg\" class=\"attachment-text_image size-text_image\" alt=\"\" srcset=\"https:\/\/www.ilcf.net\/wp-content\/uploads\/sites\/20\/2019\/11\/tandem-linguistique-esqese-ilcf-2017-ilcf-web.jpg 700w, https:\/\/www.ilcf.net\/wp-content\/uploads\/sites\/20\/2019\/11\/tandem-linguistique-esqese-ilcf-2017-ilcf-web-120x90.jpg 120w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>    <\/div>\n  <\/div>\n<\/div><p>C'est \u00e0 l'initiative de l'ESQESE que s'est mont\u00e9 un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais de l'ESQESE et \u00e9tudiants anglophones de l'ILCF. L'objectif premier est la pratique du fran\u00e7ais\/anglais sur fond d'intenses \u00e9changes culturels. L'ILCF est riche d'\u00e9tudiants de plus de <strong>90 nationalit\u00e9s.<\/strong> L\u2019ESQESE, quant \u00e0 elle, se mobilise pour sensibiliser ces \u00e9tudiants \u00e0 la diversit\u00e9 culturelle et multiplier les approches p\u00e9dagogiques li\u00e9es \u00e0 l\u2019apprentissage de l\u2019anglais.<\/p><p><strong>76 \u00e9tudiants<\/strong> sont ainsi concern\u00e9s par ce dispositif au premier semestre 2017-2018. Ce dernier concilie formation en autonomie, partage humain et dialogue interculturel. A raison d'un minimum de deux fois par mois, les 38 bin\u00f4mes vont se rencontrer et \u00e9changer <strong>dans les deux langues<\/strong> cibles en r\u00e9partissant le temps de parole.<br> Le suivi p\u00e9dagogique, r\u00e9alis\u00e9 par Nicole PILLON pour l\u2019ESQESE et Guillaume DUJARDIN pour l\u2019ILCF, est ponctu\u00e9 par la r\u00e9daction d'un cahier de bord personnel en ligne (travail r\u00e9flexif sur l'apprentissage) et par des moments de partage en pr\u00e9sence de l'enseignant. Le service Animation de l\u2019ILCF en la personne de Cristina de ALBUQUERQUE est \u00e9galement mobilis\u00e9.<\/p>","protected":false},"excerpt":{"rendered":"<p>C&#8217;est \u00e0 l&#8217;initiative de l&#8217;ESQESE que s&#8217;est mont\u00e9 un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais de l&#8217;ESQESE et \u00e9tudiants anglophones de l&#8217;ILCF. L&#8217;objectif premier [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[144],"tags":[],"class_list":["post-6693","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tandems linguistiques ILCF \/ ESQESE - ILCF - Institut de Langue et de Culture Fran\u00e7aises<\/title>\n<meta name=\"description\" content=\"Le mercredi 25 octobre 2017 a eu lieu une grande rencontre ESQESE-ILCF pour monter un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais et anglophones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tandems linguistiques ILCF \/ ESQESE - ILCF - Institut de Langue et de Culture Fran\u00e7aises\" \/>\n<meta property=\"og:description\" content=\"Le mercredi 25 octobre 2017 a eu lieu une grande rencontre ESQESE-ILCF pour monter un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais et anglophones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/\" \/>\n<meta property=\"og:site_name\" content=\"ILCF - Institut de Langue et de Culture Fran\u00e7aises\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-06T08:06:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T08:12:41+00:00\" \/>\n<meta name=\"author\" content=\"nrockenstrocly\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"nrockenstrocly\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/\"},\"author\":{\"name\":\"nrockenstrocly\",\"@id\":\"https:\/\/www.ilcf.net\/es\/#\/schema\/person\/b6830b810fa3a9b1a461d143341c683a\"},\"headline\":\"Tandems linguistiques ILCF \/ ESQESE\",\"datePublished\":\"2020-02-06T08:06:20+00:00\",\"dateModified\":\"2020-02-06T08:12:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/\"},\"wordCount\":205,\"publisher\":{\"@id\":\"https:\/\/www.ilcf.net\/es\/#organization\"},\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/\",\"url\":\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/\",\"name\":\"Tandems linguistiques ILCF \/ ESQESE - ILCF - Institut de Langue et de Culture Fran\u00e7aises\",\"isPartOf\":{\"@id\":\"https:\/\/www.ilcf.net\/es\/#website\"},\"datePublished\":\"2020-02-06T08:06:20+00:00\",\"dateModified\":\"2020-02-06T08:12:41+00:00\",\"description\":\"Le mercredi 25 octobre 2017 a eu lieu une grande rencontre ESQESE-ILCF pour monter un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais et anglophones\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ilcf.net\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tandems linguistiques ILCF \/ ESQESE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ilcf.net\/es\/#website\",\"url\":\"https:\/\/www.ilcf.net\/es\/\",\"name\":\"ILCF - Institut de Langue et de Culture Fran\u00e7aises\",\"description\":\"ILCF - Institut de Langue et de Culture Fran\u00e7aises\",\"publisher\":{\"@id\":\"https:\/\/www.ilcf.net\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ilcf.net\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ilcf.net\/es\/#organization\",\"name\":\"ILCF - Institut de Langue et de Culture Fran\u00e7aises\",\"url\":\"https:\/\/www.ilcf.net\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.ilcf.net\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ilcf.net\/wp-content\/uploads\/sites\/20\/2019\/11\/ilcf_logo.svg\",\"contentUrl\":\"https:\/\/www.ilcf.net\/wp-content\/uploads\/sites\/20\/2019\/11\/ilcf_logo.svg\",\"caption\":\"ILCF - Institut de Langue et de Culture Fran\u00e7aises\"},\"image\":{\"@id\":\"https:\/\/www.ilcf.net\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ilcf.net\/es\/#\/schema\/person\/b6830b810fa3a9b1a461d143341c683a\",\"name\":\"nrockenstrocly\",\"url\":\"https:\/\/www.ilcf.net\/es\/author\/nrockenstrocly\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tandems linguistiques ILCF \/ ESQESE - ILCF - Institut de Langue et de Culture Fran\u00e7aises","description":"Le mercredi 25 octobre 2017 a eu lieu une grande rencontre ESQESE-ILCF pour monter un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais et anglophones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/","og_locale":"es_ES","og_type":"article","og_title":"Tandems linguistiques ILCF \/ ESQESE - ILCF - Institut de Langue et de Culture Fran\u00e7aises","og_description":"Le mercredi 25 octobre 2017 a eu lieu une grande rencontre ESQESE-ILCF pour monter un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais et anglophones","og_url":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/","og_site_name":"ILCF - Institut de Langue et de Culture Fran\u00e7aises","article_published_time":"2020-02-06T08:06:20+00:00","article_modified_time":"2020-02-06T08:12:41+00:00","author":"nrockenstrocly","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"nrockenstrocly","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/#article","isPartOf":{"@id":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/"},"author":{"name":"nrockenstrocly","@id":"https:\/\/www.ilcf.net\/es\/#\/schema\/person\/b6830b810fa3a9b1a461d143341c683a"},"headline":"Tandems linguistiques ILCF \/ ESQESE","datePublished":"2020-02-06T08:06:20+00:00","dateModified":"2020-02-06T08:12:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/"},"wordCount":205,"publisher":{"@id":"https:\/\/www.ilcf.net\/es\/#organization"},"articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/","url":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/","name":"Tandems linguistiques ILCF \/ ESQESE - ILCF - Institut de Langue et de Culture Fran\u00e7aises","isPartOf":{"@id":"https:\/\/www.ilcf.net\/es\/#website"},"datePublished":"2020-02-06T08:06:20+00:00","dateModified":"2020-02-06T08:12:41+00:00","description":"Le mercredi 25 octobre 2017 a eu lieu une grande rencontre ESQESE-ILCF pour monter un dispositif de bin\u00f4mes entre \u00e9tudiants fran\u00e7ais et anglophones","breadcrumb":{"@id":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ilcf.net\/es\/tandems-linguistiques-ilcf-esqese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ilcf.net\/es\/"},{"@type":"ListItem","position":2,"name":"Tandems linguistiques ILCF \/ ESQESE"}]},{"@type":"WebSite","@id":"https:\/\/www.ilcf.net\/es\/#website","url":"https:\/\/www.ilcf.net\/es\/","name":"ILCF - Institut de Langue et de Culture Fran\u00e7aises","description":"ILCF - Institut de Langue et de Culture Fran\u00e7aises","publisher":{"@id":"https:\/\/www.ilcf.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ilcf.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ilcf.net\/es\/#organization","name":"ILCF - Institut de Langue et de Culture Fran\u00e7aises","url":"https:\/\/www.ilcf.net\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ilcf.net\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.ilcf.net\/wp-content\/uploads\/sites\/20\/2019\/11\/ilcf_logo.svg","contentUrl":"https:\/\/www.ilcf.net\/wp-content\/uploads\/sites\/20\/2019\/11\/ilcf_logo.svg","caption":"ILCF - Institut de Langue et de Culture Fran\u00e7aises"},"image":{"@id":"https:\/\/www.ilcf.net\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ilcf.net\/es\/#\/schema\/person\/b6830b810fa3a9b1a461d143341c683a","name":"nrockenstrocly","url":"https:\/\/www.ilcf.net\/es\/author\/nrockenstrocly\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/posts\/6693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/comments?post=6693"}],"version-history":[{"count":2,"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/posts\/6693\/revisions"}],"predecessor-version":[{"id":6703,"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/posts\/6693\/revisions\/6703"}],"wp:attachment":[{"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/media?parent=6693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/categories?post=6693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilcf.net\/es\/wp-json\/wp\/v2\/tags?post=6693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}